{"id":174378,"date":"2026-01-07T14:02:23","date_gmt":"2026-01-07T06:02:23","guid":{"rendered":"https:\/\/marketvalue.cn\/product\/%d8%a3%d8%af%d8%a7%d8%a9-%d8%b4%d9%88%d8%a7%d8%a1-%d9%85%d9%86-%d9%81%d9%88%d9%84%d8%a7%d8%b0-%d9%85%d9%82%d8%a7%d9%88%d9%85-%d9%84%d9%84%d8%b5%d8%af%d8%a3-%d9%85%d9%84%d9%82%d8%b7-%d8%b7%d8%b9%d8%a7\/"},"modified":"2026-07-08T11:14:39","modified_gmt":"2026-07-08T03:14:39","slug":"%d8%a3%d8%af%d8%a7%d8%a9-%d8%b4%d9%88%d8%a7%d8%a1-%d9%85%d9%86-%d9%81%d9%88%d9%84%d8%a7%d8%b0-%d9%85%d9%82%d8%a7%d9%88%d9%85-%d9%84%d9%84%d8%b5%d8%af%d8%a3-%d9%85%d9%84%d9%82%d8%b7-%d8%b7%d8%b9%d8%a7","status":"publish","type":"product","link":"https:\/\/marketvalue.cn\/ar\/product\/%d8%a3%d8%af%d8%a7%d8%a9-%d8%b4%d9%88%d8%a7%d8%a1-%d9%85%d9%86-%d9%81%d9%88%d9%84%d8%a7%d8%b0-%d9%85%d9%82%d8%a7%d9%88%d9%85-%d9%84%d9%84%d8%b5%d8%af%d8%a3-%d9%85%d9%84%d9%82%d8%b7-%d8%b7%d8%b9%d8%a7\/","title":{"rendered":"\u0623\u062f\u0627\u0629 \u0634\u0648\u0627\u0621 \u0645\u0646 \u0641\u0648\u0644\u0627\u0630 \u0645\u0642\u0627\u0648\u0645 \u0644\u0644\u0635\u062f\u0623 \u0645\u0644\u0642\u0637 \u0637\u0639\u0627\u0645 \u0648\u0642\u0644\u0651\u0627\u0628\u0629"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong>\u0627\u0644\u0648\u0635\u0641\uff1a<\/strong>\u0623\u062f\u0627\u0629 \u0634\u0648\u0627\u0621 \u0645\u0646 \u0641\u0648\u0644\u0627\u0630 \u0645\u0642\u0627\u0648\u0645 \u0644\u0644\u0635\u062f\u0623 \u0645\u0644\u0642\u0637 \u0637\u0639\u0627\u0645 \u0648\u0642\u0644\u0651\u0627\u0628\u0629<\/p>\n<p> <strong>\u0627\u0644\u0645\u0642\u0627\u0633\uff1a<\/strong><\/p>\n<p> <strong>\u0633\u0639\u0631 \u0627\u0644\u0648\u062d\u062f\u0629 (USD)\uff1a<\/strong>1.05<\/p>\n<p> <strong>\u0627\u0644\u062d\u062f \u0627\u0644\u0623\u062f\u0646\u0649 \u0644\u0644\u0637\u0644\u0628\uff1a<\/strong>3000<\/p>\n<p> <strong>\u0627\u0644\u0643\u0645\u064a\u0629\/\u0627\u0644\u0643\u0631\u062a\u0648\u0646\uff1a<\/strong>72SETS<\/p>\n<p> <strong>\u0627\u0644\u062d\u062c\u0645 \u0628\u0627\u0644\u0645\u062a\u0631 \u0627\u0644\u0645\u0643\u0639\u0628\uff1a<\/strong>0.066<\/p>\n","protected":false},"featured_media":3383,"comment_status":"closed","ping_status":"open","template":"","meta":{"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[2448],"product_tag":[2702,2669,2661,2683],"class_list":["post-174378","product","type-product","status-publish","has-post-thumbnail","product_cat-bbq-tool-sets-ar","product_tag-grill-tool-ar","product_tag-outdoor-cooking-ar","product_tag-plastic-ar","product_tag-wholesale-ar","first","instock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product\/174378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/comments?post=174378"}],"version-history":[{"count":0,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product\/174378\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/media\/3383"}],"wp:attachment":[{"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/media?parent=174378"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product_brand?post=174378"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product_cat?post=174378"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product_tag?post=174378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}