{"id":176135,"date":"2026-01-07T14:10:08","date_gmt":"2026-01-07T06:10:08","guid":{"rendered":"https:\/\/marketvalue.cn\/product\/%d8%a3%d8%af%d9%88%d8%a7%d8%aa-%d9%85%d8%b7%d8%a8%d8%ae-%d9%86%d8%a7%d9%8a%d9%84%d9%88%d9%86-%d9%85%d9%83%d8%a8%d8%b3-%d8%a8%d8%b7%d8%a7%d8%b7%d8%b3\/"},"modified":"2026-07-08T11:25:48","modified_gmt":"2026-07-08T03:25:48","slug":"%d8%a3%d8%af%d9%88%d8%a7%d8%aa-%d9%85%d8%b7%d8%a8%d8%ae-%d9%86%d8%a7%d9%8a%d9%84%d9%88%d9%86-%d9%85%d9%83%d8%a8%d8%b3-%d8%a8%d8%b7%d8%a7%d8%b7%d8%b3","status":"publish","type":"product","link":"https:\/\/marketvalue.cn\/ar\/product\/%d8%a3%d8%af%d9%88%d8%a7%d8%aa-%d9%85%d8%b7%d8%a8%d8%ae-%d9%86%d8%a7%d9%8a%d9%84%d9%88%d9%86-%d9%85%d9%83%d8%a8%d8%b3-%d8%a8%d8%b7%d8%a7%d8%b7%d8%b3\/","title":{"rendered":"\u0623\u062f\u0648\u0627\u062a \u0645\u0637\u0628\u062e \u0646\u0627\u064a\u0644\u0648\u0646 \/ \u0645\u0643\u0628\u0633 \u0628\u0637\u0627\u0637\u0633"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong>\u0627\u0644\u0648\u0635\u0641\uff1a<\/strong>\u0623\u062f\u0648\u0627\u062a \u0645\u0637\u0628\u062e \u0646\u0627\u064a\u0644\u0648\u0646 \/ \u0645\u0643\u0628\u0633 \u0628\u0637\u0627\u0637\u0633<\/p>\n<p> <strong>\u0627\u0644\u0645\u0642\u0627\u0633\uff1a<\/strong>\u0627\u0644\u0645\u0642\u0627\u0633:25X10CM,65G,\u0627\u0644\u0645\u0642\u0628\u0636:11.5CM<\/p>\n<p> <strong>\u0633\u0639\u0631 \u0627\u0644\u0648\u062d\u062f\u0629 (USD)\uff1a<\/strong>0.19<\/p>\n<p> <strong>\u0627\u0644\u062d\u062f \u0627\u0644\u0623\u062f\u0646\u0649 \u0644\u0644\u0637\u0644\u0628\uff1a<\/strong>3000<\/p>\n<p> <strong>\u0627\u0644\u0643\u0645\u064a\u0629\/\u0627\u0644\u0643\u0631\u062a\u0648\u0646\uff1a<\/strong>144PCS.<\/p>\n<p> <strong>\u0627\u0644\u062d\u062c\u0645 \u0628\u0627\u0644\u0645\u062a\u0631 \u0627\u0644\u0645\u0643\u0639\u0628\uff1a<\/strong>0.0489<\/p>\n","protected":false},"featured_media":6893,"comment_status":"closed","ping_status":"open","template":"","meta":{"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[2492],"product_tag":[2661,2667,2683,2666],"class_list":["post-176135","product","type-product","status-publish","has-post-thumbnail","product_cat-cooking-utensils-ar","product_tag-plastic-ar","product_tag-food-prep-ar","product_tag-wholesale-ar","product_tag-home-kitchen-ar","first","instock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product\/176135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/comments?post=176135"}],"version-history":[{"count":0,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product\/176135\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/media\/6893"}],"wp:attachment":[{"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/media?parent=176135"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product_brand?post=176135"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product_cat?post=176135"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product_tag?post=176135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}