{"id":203074,"date":"2026-01-07T15:48:04","date_gmt":"2026-01-07T07:48:04","guid":{"rendered":"https:\/\/marketvalue.cn\/product\/%d9%84%d9%88%d8%ad-%d8%aa%d9%82%d8%b7%d9%8a%d8%b9-%d8%a8%d9%84%d8%a7%d8%b3%d8%aa%d9%8a%d9%83-%d9%85%d9%82%d8%a7%d8%b3-10-%d8%a8%d9%88%d8%b5%d8%a9%d8%8c-%d8%a8%d8%b7%d8%a7%d9%82%d8%a9-%d8%b9%d8%ac\/"},"modified":"2026-07-08T16:27:39","modified_gmt":"2026-07-08T08:27:39","slug":"%d9%84%d9%88%d8%ad-%d8%aa%d9%82%d8%b7%d9%8a%d8%b9-%d8%a8%d9%84%d8%a7%d8%b3%d8%aa%d9%8a%d9%83-%d9%85%d9%82%d8%a7%d8%b3-10-%d8%a8%d9%88%d8%b5%d8%a9%d8%8c-%d8%a8%d8%b7%d8%a7%d9%82%d8%a9-%d8%b9%d8%ac","status":"publish","type":"product","link":"https:\/\/marketvalue.cn\/ar\/product\/%d9%84%d9%88%d8%ad-%d8%aa%d9%82%d8%b7%d9%8a%d8%b9-%d8%a8%d9%84%d8%a7%d8%b3%d8%aa%d9%8a%d9%83-%d9%85%d9%82%d8%a7%d8%b3-10-%d8%a8%d9%88%d8%b5%d8%a9%d8%8c-%d8%a8%d8%b7%d8%a7%d9%82%d8%a9-%d8%b9%d8%ac\/","title":{"rendered":"\u0644\u0648\u062d \u062a\u0642\u0637\u064a\u0639 \u0628\u0644\u0627\u0633\u062a\u064a\u0643 \u0645\u0642\u0627\u0633 10 \u0628\u0648\u0635\u0629\u060c \u0628\u0637\u0627\u0642\u0629 \u0639\u062c\u0644\u0629"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong>\u0627\u0644\u0648\u0635\u0641\uff1a<\/strong>\u0644\u0648\u062d \u062a\u0642\u0637\u064a\u0639 \u0628\u0644\u0627\u0633\u062a\u064a\u0643 \u0645\u0642\u0627\u0633 10 \u0628\u0648\u0635\u0629\u060c \u0628\u0637\u0627\u0642\u0629 \u0639\u062c\u0644\u0629<\/p>\n<p> <strong>\u0627\u0644\u0645\u0642\u0627\u0633\uff1a<\/strong>25*15*0.8cm 247g<\/p>\n<p> <strong>\u0633\u0639\u0631 \u0627\u0644\u0648\u062d\u062f\u0629 (USD)\uff1a<\/strong>0.9<\/p>\n<p> <strong>\u0627\u0644\u062d\u062f \u0627\u0644\u0623\u062f\u0646\u0649 \u0644\u0644\u0637\u0644\u0628\uff1a<\/strong>3000<\/p>\n<p> <strong>\u0627\u0644\u0643\u0645\u064a\u0629\/\u0627\u0644\u0643\u0631\u062a\u0648\u0646\uff1a<\/strong>48SETS<\/p>\n<p> <strong>\u0627\u0644\u062d\u062c\u0645 \u0628\u0627\u0644\u0645\u062a\u0631 \u0627\u0644\u0645\u0643\u0639\u0628\uff1a<\/strong>0.019<\/p>\n","protected":false},"featured_media":14881,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[2457],"product_tag":[2661,2667,2703,2683,2666],"class_list":["post-203074","product","type-product","status-publish","has-post-thumbnail","product_cat-cutting-boards-ar","product_tag-plastic-ar","product_tag-food-prep-ar","product_tag-retail-packaging-ar","product_tag-wholesale-ar","product_tag-home-kitchen-ar","first","instock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product\/203074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/comments?post=203074"}],"version-history":[{"count":1,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product\/203074\/revisions"}],"predecessor-version":[{"id":208059,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product\/203074\/revisions\/208059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/media\/14881"}],"wp:attachment":[{"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/media?parent=203074"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product_brand?post=203074"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product_cat?post=203074"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/marketvalue.cn\/ar\/wp-json\/wp\/v2\/product_tag?post=203074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}